{"id":5295,"date":"2025-05-07T15:31:08","date_gmt":"2025-05-07T13:31:08","guid":{"rendered":"https:\/\/dlb-aoer.de\/neu-isenburg\/?p=5295"},"modified":"2025-05-07T15:32:32","modified_gmt":"2025-05-07T13:32:32","slug":"sauberhafter-kindertag-3","status":"publish","type":"post","link":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/","title":{"rendered":"Sauberhafter Kindertag"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5295\" class=\"elementor elementor-5295\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-122f463 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"122f463\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c190670\" data-id=\"c190670\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d8df8c elementor-widget elementor-widget-text-editor\" data-id=\"7d8df8c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Neu-Isenburger Kitas haben ein Zeichen f\u00fcr den Umweltschutz gesetzt!<\/strong><\/p><p>Am \u201eSauberhaften Kindertag\u201c waren wieder die Umweltsch\u00fctzer von morgen unterwegs.<\/p><p>An diesem Aktionstag haben sich Hunderte Kindertagesst\u00e4tten in ganz Hessen auf den Weg gemacht und gemeinsam rund um die Kindertagesst\u00e4tte Abfall gesammelt.<\/p><p>In Neu-Isenburg waren sechs Kitas mit insgesamt 200 Kindern unterwegs. Die Kinder waren hochmotiviert und sind ausger\u00fcstet mit Handschuhen und M\u00fcllzangen auf die Jagd nach M\u00fcll gegangen. Einige Kitas sammelten im direkten Umfeld der Einrichtung, andere erweiterten ihr Sammelgebiet. So wurde beispielsweise der Dreiherrnsteinplatz, die Hugenottenallee, der Sportpark sowie einige ausgew\u00e4hlte Spielpl\u00e4tzen vom M\u00fcll befreit.<\/p><p>Leider mussten die Kinder auch in diesem Jahr feststellen, dass sich die mitgebrachten M\u00fcllt\u00fcten schnell mit herumliegendem Abfall f\u00fcllten. Die Kitas berichten von gro\u00dfen Mengen Zigarettenkippen auf Gehwegen und leider auch auf den Spielpl\u00e4tzen im Sand.<\/p><p>Eine besondere \u00dcberraschung gab es f\u00fcr die M\u00fcllsammler der katholischen Kita St. Franziskus. Das DLB Maskottchen \u201eLutz van Putz\u201c war unterwegs und hat die Kinder vor dem Kindergarten getroffen. Auch Stefan Schmitt, Erster Stadtrat der Stadt Neu-Isenburg war dabei und bedankte sich bei den Kindern f\u00fcr Ihren Einsatz. Die Freude \u00fcber diesen hohen Besuch war gro\u00df! Nach der Sammelaktion haben sich die Kinder gefragt, warum so viel M\u00fcll und Zigaretten einfach in die Natur geschmissen werden. Stefan Schmitt, Erster Stadtrat der Stadt Neu-Isenburg bedankt sich bei allen teilnehmenden Kitas: \u201eEs ist sch\u00f6n zu sehen, wie engagiert die Kleinsten unserer Gesellschaft in Sachen Umweltschutz vorangehen! Es ist nicht selbstverst\u00e4ndlich den M\u00fcll anderer Leute wegzur\u00e4umen, daf\u00fcr m\u00f6chte ich mich recht herzlich bedanken!\u201c Der sauberhafte Kindertag ist eine wichtige Erfahrung f\u00fcr die Kleinen. Durch die Aktion k\u00f6nnen Kinder erleben, dass ihr eigenes Handeln etwas bewegt.<\/p><p>Der \u201eSauberhafte Kindertag\u201c findet j\u00e4hrlich im Rahmen der Umweltkampagne der Hessischen Landesregierung \u201eSauberhaftes Hessen\u201c statt. Ziel der Kampagne ist es, das Bewusstsein f\u00fcr eine intakte Umwelt, den Wert von Ressourcen und die Wichtigkeit von Abfallvermeidung zu sch\u00e4rfen. Seit 2002 haben jedes Jahr tausende hessische B\u00fcrgerinnen und B\u00fcrger bei unz\u00e4hligen Sammelaktionen selbst Hand angelegt und verschmutzte Fl\u00e4chen von Abf\u00e4llen befreit.<\/p><p>\u00a0<\/p><p>Am 01. Juli startet die n\u00e4chste sauberhafte Aktion! Demn\u00e4chst werden alle Schulen in Neu-Isenburg eingeladen daran teilzunehmen. Nat\u00fcrlich auch wieder mit DLB-Unterst\u00fctzung!<\/p><p>Mehr Informationen finden Sie unter <a href=\"http:\/\/www.dlb-aoer.de\">www.dlb-aoer.de<\/a> oder sauberhaftes-hessen.de.<\/p><p>Folgende Einrichtungen waren am 6. Mai in Neu-Isenburg dabei:<\/p><p>Ev. Kita Johannesgemeinde, ev. Kita Gravenbruch, Kita Kaleidoskop, kath. Kita St. Franziskus, Kita Zeppelinheim, Familienzentrum Kurt-Schumacher-Str.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Neu-Isenburger Kitas haben ein Zeichen f\u00fcr den Umweltschutz gesetzt! Am \u201eSauberhaften Kindertag\u201c waren wieder die Umweltsch\u00fctzer von morgen unterwegs. An diesem Aktionstag [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-5295","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sauberhafter Kindertag - DLB Neu-Isenburg<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sauberhafter Kindertag - DLB Neu-Isenburg\" \/>\n<meta property=\"og:description\" content=\"Neu-Isenburger Kitas haben ein Zeichen f\u00fcr den Umweltschutz gesetzt! Am \u201eSauberhaften Kindertag\u201c waren wieder die Umweltsch\u00fctzer von morgen unterwegs. An diesem Aktionstag [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/\" \/>\n<meta property=\"og:site_name\" content=\"DLB Neu-Isenburg\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T13:31:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T13:32:32+00:00\" \/>\n<meta name=\"author\" content=\"dlbcontent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"dlbcontent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/\"},\"author\":{\"name\":\"dlbcontent\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/person\/ace12b78b8beb2c401214583e8abb0ea\"},\"headline\":\"Sauberhafter Kindertag\",\"datePublished\":\"2025-05-07T13:31:08+00:00\",\"dateModified\":\"2025-05-07T13:32:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/\"},\"wordCount\":428,\"publisher\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/\",\"url\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/\",\"name\":\"Sauberhafter Kindertag - DLB Neu-Isenburg\",\"isPartOf\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#website\"},\"datePublished\":\"2025-05-07T13:31:08+00:00\",\"dateModified\":\"2025-05-07T13:32:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sauberhafter Kindertag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#website\",\"url\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/\",\"name\":\"DLB Neu-Isenburg\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#organization\",\"name\":\"Dienstleistungsbetrieb Dreieich und Neu-Isenburg A\u00f6R\",\"url\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-content\/uploads\/sites\/2\/2019\/10\/DLB_Logo_orange.svg\",\"contentUrl\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-content\/uploads\/sites\/2\/2019\/10\/DLB_Logo_orange.svg\",\"width\":1,\"height\":1,\"caption\":\"Dienstleistungsbetrieb Dreieich und Neu-Isenburg A\u00f6R\"},\"image\":{\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/person\/ace12b78b8beb2c401214583e8abb0ea\",\"name\":\"dlbcontent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9b83944ad4bb586f5b061e177ec90421c57dc65897720d856030931fc4ed8394?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9b83944ad4bb586f5b061e177ec90421c57dc65897720d856030931fc4ed8394?s=96&d=mm&r=g\",\"caption\":\"dlbcontent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sauberhafter Kindertag - DLB Neu-Isenburg","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Sauberhafter Kindertag - DLB Neu-Isenburg","og_description":"Neu-Isenburger Kitas haben ein Zeichen f\u00fcr den Umweltschutz gesetzt! Am \u201eSauberhaften Kindertag\u201c waren wieder die Umweltsch\u00fctzer von morgen unterwegs. An diesem Aktionstag [&hellip;]","og_url":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/","og_site_name":"DLB Neu-Isenburg","article_published_time":"2025-05-07T13:31:08+00:00","article_modified_time":"2025-05-07T13:32:32+00:00","author":"dlbcontent","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"dlbcontent","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/#article","isPartOf":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/"},"author":{"name":"dlbcontent","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/person\/ace12b78b8beb2c401214583e8abb0ea"},"headline":"Sauberhafter Kindertag","datePublished":"2025-05-07T13:31:08+00:00","dateModified":"2025-05-07T13:32:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/"},"wordCount":428,"publisher":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#organization"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/","url":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/","name":"Sauberhafter Kindertag - DLB Neu-Isenburg","isPartOf":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#website"},"datePublished":"2025-05-07T13:31:08+00:00","dateModified":"2025-05-07T13:32:32+00:00","breadcrumb":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/sauberhafter-kindertag-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dlb-aoer.de\/neu-isenburg\/"},{"@type":"ListItem","position":2,"name":"Sauberhafter Kindertag"}]},{"@type":"WebSite","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#website","url":"https:\/\/dlb-aoer.de\/neu-isenburg\/","name":"DLB Neu-Isenburg","description":"","publisher":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlb-aoer.de\/neu-isenburg\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#organization","name":"Dienstleistungsbetrieb Dreieich und Neu-Isenburg A\u00f6R","url":"https:\/\/dlb-aoer.de\/neu-isenburg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/logo\/image\/","url":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-content\/uploads\/sites\/2\/2019\/10\/DLB_Logo_orange.svg","contentUrl":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-content\/uploads\/sites\/2\/2019\/10\/DLB_Logo_orange.svg","width":1,"height":1,"caption":"Dienstleistungsbetrieb Dreieich und Neu-Isenburg A\u00f6R"},"image":{"@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/person\/ace12b78b8beb2c401214583e8abb0ea","name":"dlbcontent","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dlb-aoer.de\/neu-isenburg\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9b83944ad4bb586f5b061e177ec90421c57dc65897720d856030931fc4ed8394?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b83944ad4bb586f5b061e177ec90421c57dc65897720d856030931fc4ed8394?s=96&d=mm&r=g","caption":"dlbcontent"}}]}},"_links":{"self":[{"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/posts\/5295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/comments?post=5295"}],"version-history":[{"count":4,"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/posts\/5295\/revisions"}],"predecessor-version":[{"id":5299,"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/posts\/5295\/revisions\/5299"}],"wp:attachment":[{"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/media?parent=5295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/categories?post=5295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlb-aoer.de\/neu-isenburg\/wp-json\/wp\/v2\/tags?post=5295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}